{"id":63,"date":"2021-10-20T14:42:14","date_gmt":"2021-10-20T12:42:14","guid":{"rendered":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/produit\/jus-dananas-bio-75-cl\/"},"modified":"2026-09-01T17:00:53","modified_gmt":"2026-09-01T15:00:53","slug":"jus-dananas-bio-75-cl","status":"publish","type":"product","link":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/produit\/jus-dananas-bio-75-cl\/","title":{"rendered":"Jus d&rsquo;ananas bio 75 CL"},"content":{"rendered":"<table>\n<tbody>\n<tr>\n<td><span class=\"item-name\">Energie kJ<\/span><\/td>\n<td><strong class=\"item-value\">242<\/strong>\u00a0<small class=\"item-notice\">\/ 100 ml<\/small><\/td>\n<\/tr>\n<tr>\n<td><span class=\"item-name\">Energie kcal<\/span><\/td>\n<td><strong class=\"item-value\">57<\/strong>\u00a0<small class=\"item-notice\">\/ 100 ml<\/small><\/td>\n<\/tr>\n<tr>\n<td><span class=\"item-name\">Mati\u00e8res grasses<\/span><\/td>\n<td><strong class=\"item-value\">0<\/strong>\u00a0<small class=\"item-notice\">\/ 100 ml<\/small><\/td>\n<\/tr>\n<tr>\n<td><span class=\"item-name\">Sucres<\/span><\/td>\n<td><strong class=\"item-value\">12,4<\/strong>\u00a0<small class=\"item-notice\">\/ 100 ml<\/small><\/td>\n<\/tr>\n<tr>\n<td><span class=\"item-name\">Prot\u00e9ines<\/span><\/td>\n<td><strong class=\"item-value\">0<\/strong>\u00a0<small class=\"item-notice\">\/ 100 ml<\/small><\/td>\n<\/tr>\n<tr>\n<td><span class=\"item-name\">Sel<\/span><\/td>\n<td><strong class=\"item-value\">0<\/strong>\u00a0<small class=\"item-notice\">\/ 100 ml<\/small><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Coteaux Nantais &#8211; \u00a0Jus doux et savoureux \u00e0 consommer pour une pause ensoleill\u00e9e<\/p>\n","protected":false},"featured_media":472,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[19,20],"product_tag":[],"class_list":{"0":"post-63","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-boisson","7":"product_cat-softs","8":"criterion-carte-automne-hiver","9":"criterion-carte-de-noel","10":"criterion-carte-festive","11":"criterion-carte-printemps-ete","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"composite_virtual":false,"composite_layout":"","composite_add_to_cart_form_location":"","composite_editable_in_cart":false,"composite_sold_individually_context":"","composite_shop_price_calc":"","composite_components":[],"composite_scenarios":[],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","acf":[],"_links":{"self":[{"href":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/wp-json\/wp\/v2\/product\/63","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/wp-json\/wp\/v2\/comments?post=63"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/wp-json\/wp\/v2\/media\/472"}],"wp:attachment":[{"href":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/wp-json\/wp\/v2\/media?parent=63"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/wp-json\/wp\/v2\/product_brand?post=63"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/wp-json\/wp\/v2\/product_cat?post=63"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/wp-json\/wp\/v2\/product_tag?post=63"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}