{"id":37,"date":"2021-10-20T14:42:08","date_gmt":"2021-10-20T12:42:08","guid":{"rendered":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/produit\/demi-badoit\/"},"modified":"2026-09-01T17:00:50","modified_gmt":"2026-09-01T15:00:50","slug":"demi-badoit","status":"publish","type":"product","link":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/produit\/demi-badoit\/","title":{"rendered":"Demi Badoit"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Eau p\u00e9tillante, bouteille en plastique. Format individuel pour accompagner un d\u00e9jeuner !<\/p>\n","protected":false},"featured_media":461,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[19,20],"product_tag":[],"class_list":{"0":"post-37","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-boisson","7":"product_cat-softs","8":"criterion-carte-automne-hiver","9":"criterion-carte-de-noel","10":"criterion-carte-festive","11":"criterion-carte-printemps-ete","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"composite_virtual":false,"composite_layout":"","composite_add_to_cart_form_location":"","composite_editable_in_cart":false,"composite_sold_individually_context":"","composite_shop_price_calc":"","composite_components":[],"composite_scenarios":[],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","acf":[],"_links":{"self":[{"href":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/wp-json\/wp\/v2\/product\/37","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/wp-json\/wp\/v2\/comments?post=37"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/wp-json\/wp\/v2\/media\/461"}],"wp:attachment":[{"href":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/wp-json\/wp\/v2\/media?parent=37"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/wp-json\/wp\/v2\/product_brand?post=37"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/wp-json\/wp\/v2\/product_cat?post=37"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.brisontraiteur.com\/carte-des-fetes\/wp-json\/wp\/v2\/product_tag?post=37"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}